{"id":16033,"date":"2025-07-31T07:02:13","date_gmt":"2025-07-31T07:02:13","guid":{"rendered":"https:\/\/www.originalphotopaper.com\/?p=16033"},"modified":"2025-07-31T07:02:14","modified_gmt":"2025-07-31T07:02:14","slug":"lotte-van-alderen-dog-photography","status":"publish","type":"post","link":"https:\/\/www.originalphotopaper.com\/pl\/beyond-the-lens\/lotte-van-alderen-dog-photography\/","title":{"rendered":"Lotte van Alderen. Foscofotografie"},"content":{"rendered":"<section class=\"container\">\n\t<div class=\"full-video full-video--block\">\n    <div class=\"full-video__intro c-content\">\n            <\/div>\n    <div class=\"full-video__viewport\" data-behaviour=\"video-container\">\n        <video class=\"full-video__hero\" width=\"1920\" height=\"1024\" data-behaviour=\"video\" playsinline controls disablepictureinpicture controlslist=\"nodownload noplaybackrate\"\n                                >\n                            <source src=\"https:\/\/player.vimeo.com\/progressive_redirect\/playback\/1060814275\/rendition\/1080p\/file.mp4?loc=external&#038;signature=62311e15739bbc620971fa809dc739ac3bec44a84ed25e75d3594ff26bfc420f\" type=\"video\/webm\" \/>\n                             <source src=\"https:\/\/vimeo.com\/manage\/videos\/1062440037\/f002bf9c71\" type=\"video\/mp4\" \/>\n                    <\/video>\n\n            <\/div>\n<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p><b>Beyond the Lens<\/b><\/p>\n<p>Zobacz, jak profesjonalni fotografowie wychodz\u0105 poza kadr, dziel\u0105c si\u0119 cennymi spostrze\u017ceniami i prowadz\u0105c Ci\u0119 krok po kroku przez proces tw\u00f3rczej produkcji.<\/p>\n<p>Prezentuj\u0105 oni zalety konkretnych rodzaj\u00f3w papieru fotograficznego, szczeg\u00f3\u0142owo opisuj\u0105c swoje ko\u0144cowe produkty, aby przekszta\u0142ci\u0107 swoje kreatywne wizje w zachwycaj\u0105ce dzie\u0142a sztuki.<\/p>\n","protected":false},"author":4,"featured_media":16017,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":true,"footnotes":""},"categories":[107],"tags":[],"class_list":["post-16033","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beyond-the-lens"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lotte van Alderen. Foscofotografie - Original Photo Paper by FUJIFILM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.originalphotopaper.com\/pl\/beyond-the-lens\/lotte-van-alderen-dog-photography\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lotte van Alderen. Foscofotografie - Original Photo Paper by FUJIFILM\" \/>\n<meta property=\"og:description\" content=\"Beyond the LensZobacz, jak profesjonalni fotografowie wychodz\u0105 poza kadr, dziel\u0105c si\u0119 cennymi spostrze\u017ceniami i prowadz\u0105c Ci\u0119 krok po kroku przez proces tw\u00f3rczej produkcji. Prezentuj\u0105 oni zalety konkretnych rodzaj\u00f3w papieru fotograficznego, szczeg\u00f3\u0142owo opisuj\u0105c swoje ko\u0144cowe produkty, aby przekszta\u0142ci\u0107 swoje kreatywne wizje w zachwycaj\u0105ce dzie\u0142a sztuki.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.originalphotopaper.com\/pl\/beyond-the-lens\/lotte-van-alderen-dog-photography\/\" \/>\n<meta property=\"og:site_name\" content=\"Original Photo Paper by FUJIFILM\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-31T07:02:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-31T07:02:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.originalphotopaper.com\/wp-content\/uploads\/2025\/07\/Lotte-adjusted-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arjen Janssen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arjen Janssen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.originalphotopaper.com\\\/pl\\\/beyond-the-lens\\\/lotte-van-alderen-dog-photography\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.originalphotopaper.com\\\/pl\\\/beyond-the-lens\\\/lotte-van-alderen-dog-photography\\\/\"},\"author\":{\"name\":\"Arjen Janssen\",\"@id\":\"https:\\\/\\\/www.originalphotopaper.com\\\/pl\\\/#\\\/schema\\\/person\\\/de751a26f5badc585d47e1934d237e47\"},\"headline\":\"Lotte van Alderen. Foscofotografie\",\"datePublished\":\"2025-07-31T07:02:13+00:00\",\"dateModified\":\"2025-07-31T07:02:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.originalphotopaper.com\\\/pl\\\/beyond-the-lens\\\/lotte-van-alderen-dog-photography\\\/\"},\"wordCount\":4,\"image\":{\"@id\":\"https:\\\/\\\/www.originalphotopaper.com\\\/pl\\\/beyond-the-lens\\\/lotte-van-alderen-dog-photography\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.originalphotopaper.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Lotte-adjusted-scaled.jpg\",\"articleSection\":[\"Beyond the Lens\"],\"inLanguage\":\"pl-PL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.originalphotopaper.com\\\/pl\\\/beyond-the-lens\\\/lotte-van-alderen-dog-photography\\\/\",\"url\":\"https:\\\/\\\/www.originalphotopaper.com\\\/pl\\\/beyond-the-lens\\\/lotte-van-alderen-dog-photography\\\/\",\"name\":\"Lotte van Alderen. Foscofotografie - Original Photo Paper by FUJIFILM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.originalphotopaper.com\\\/pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.originalphotopaper.com\\\/pl\\\/beyond-the-lens\\\/lotte-van-alderen-dog-photography\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.originalphotopaper.com\\\/pl\\\/beyond-the-lens\\\/lotte-van-alderen-dog-photography\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.originalphotopaper.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Lotte-adjusted-scaled.jpg\",\"datePublished\":\"2025-07-31T07:02:13+00:00\",\"dateModified\":\"2025-07-31T07:02:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.originalphotopaper.com\\\/pl\\\/#\\\/schema\\\/person\\\/de751a26f5badc585d47e1934d237e47\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.originalphotopaper.com\\\/pl\\\/beyond-the-lens\\\/lotte-van-alderen-dog-photography\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.originalphotopaper.com\\\/pl\\\/beyond-the-lens\\\/lotte-van-alderen-dog-photography\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/www.originalphotopaper.com\\\/pl\\\/beyond-the-lens\\\/lotte-van-alderen-dog-photography\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.originalphotopaper.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Lotte-adjusted-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.originalphotopaper.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Lotte-adjusted-scaled.jpg\",\"width\":2560,\"height\":2350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.originalphotopaper.com\\\/pl\\\/beyond-the-lens\\\/lotte-van-alderen-dog-photography\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Dom\",\"item\":\"https:\\\/\\\/www.originalphotopaper.com\\\/pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lotte van Alderen. Foscofotogr&hellip;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.originalphotopaper.com\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/www.originalphotopaper.com\\\/pl\\\/\",\"name\":\"Original Photo Paper by FUJIFILM\",\"description\":\"DISCOVER FUJIFILM ORIGINAL PHOTOGRAPHIC PAPERS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.originalphotopaper.com\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.originalphotopaper.com\\\/pl\\\/#\\\/schema\\\/person\\\/de751a26f5badc585d47e1934d237e47\",\"name\":\"Arjen Janssen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c9ddd5c119251f85fa34754a0dc67669f83c5e8594bd5650418c63a71343b6e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c9ddd5c119251f85fa34754a0dc67669f83c5e8594bd5650418c63a71343b6e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c9ddd5c119251f85fa34754a0dc67669f83c5e8594bd5650418c63a71343b6e?s=96&d=mm&r=g\",\"caption\":\"Arjen Janssen\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lotte van Alderen. Foscofotografie - Original Photo Paper by FUJIFILM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.originalphotopaper.com\/pl\/beyond-the-lens\/lotte-van-alderen-dog-photography\/","og_locale":"pl_PL","og_type":"article","og_title":"Lotte van Alderen. Foscofotografie - Original Photo Paper by FUJIFILM","og_description":"Beyond the LensZobacz, jak profesjonalni fotografowie wychodz\u0105 poza kadr, dziel\u0105c si\u0119 cennymi spostrze\u017ceniami i prowadz\u0105c Ci\u0119 krok po kroku przez proces tw\u00f3rczej produkcji. Prezentuj\u0105 oni zalety konkretnych rodzaj\u00f3w papieru fotograficznego, szczeg\u00f3\u0142owo opisuj\u0105c swoje ko\u0144cowe produkty, aby przekszta\u0142ci\u0107 swoje kreatywne wizje w zachwycaj\u0105ce dzie\u0142a sztuki.","og_url":"https:\/\/www.originalphotopaper.com\/pl\/beyond-the-lens\/lotte-van-alderen-dog-photography\/","og_site_name":"Original Photo Paper by FUJIFILM","article_published_time":"2025-07-31T07:02:13+00:00","article_modified_time":"2025-07-31T07:02:14+00:00","og_image":[{"width":2560,"height":2350,"url":"https:\/\/www.originalphotopaper.com\/wp-content\/uploads\/2025\/07\/Lotte-adjusted-scaled.jpg","type":"image\/jpeg"}],"author":"Arjen Janssen","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Arjen Janssen","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.originalphotopaper.com\/pl\/beyond-the-lens\/lotte-van-alderen-dog-photography\/#article","isPartOf":{"@id":"https:\/\/www.originalphotopaper.com\/pl\/beyond-the-lens\/lotte-van-alderen-dog-photography\/"},"author":{"name":"Arjen Janssen","@id":"https:\/\/www.originalphotopaper.com\/pl\/#\/schema\/person\/de751a26f5badc585d47e1934d237e47"},"headline":"Lotte van Alderen. Foscofotografie","datePublished":"2025-07-31T07:02:13+00:00","dateModified":"2025-07-31T07:02:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.originalphotopaper.com\/pl\/beyond-the-lens\/lotte-van-alderen-dog-photography\/"},"wordCount":4,"image":{"@id":"https:\/\/www.originalphotopaper.com\/pl\/beyond-the-lens\/lotte-van-alderen-dog-photography\/#primaryimage"},"thumbnailUrl":"https:\/\/www.originalphotopaper.com\/wp-content\/uploads\/2025\/07\/Lotte-adjusted-scaled.jpg","articleSection":["Beyond the Lens"],"inLanguage":"pl-PL"},{"@type":"WebPage","@id":"https:\/\/www.originalphotopaper.com\/pl\/beyond-the-lens\/lotte-van-alderen-dog-photography\/","url":"https:\/\/www.originalphotopaper.com\/pl\/beyond-the-lens\/lotte-van-alderen-dog-photography\/","name":"Lotte van Alderen. Foscofotografie - Original Photo Paper by FUJIFILM","isPartOf":{"@id":"https:\/\/www.originalphotopaper.com\/pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.originalphotopaper.com\/pl\/beyond-the-lens\/lotte-van-alderen-dog-photography\/#primaryimage"},"image":{"@id":"https:\/\/www.originalphotopaper.com\/pl\/beyond-the-lens\/lotte-van-alderen-dog-photography\/#primaryimage"},"thumbnailUrl":"https:\/\/www.originalphotopaper.com\/wp-content\/uploads\/2025\/07\/Lotte-adjusted-scaled.jpg","datePublished":"2025-07-31T07:02:13+00:00","dateModified":"2025-07-31T07:02:14+00:00","author":{"@id":"https:\/\/www.originalphotopaper.com\/pl\/#\/schema\/person\/de751a26f5badc585d47e1934d237e47"},"breadcrumb":{"@id":"https:\/\/www.originalphotopaper.com\/pl\/beyond-the-lens\/lotte-van-alderen-dog-photography\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.originalphotopaper.com\/pl\/beyond-the-lens\/lotte-van-alderen-dog-photography\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/www.originalphotopaper.com\/pl\/beyond-the-lens\/lotte-van-alderen-dog-photography\/#primaryimage","url":"https:\/\/www.originalphotopaper.com\/wp-content\/uploads\/2025\/07\/Lotte-adjusted-scaled.jpg","contentUrl":"https:\/\/www.originalphotopaper.com\/wp-content\/uploads\/2025\/07\/Lotte-adjusted-scaled.jpg","width":2560,"height":2350},{"@type":"BreadcrumbList","@id":"https:\/\/www.originalphotopaper.com\/pl\/beyond-the-lens\/lotte-van-alderen-dog-photography\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Dom","item":"https:\/\/www.originalphotopaper.com\/pl\/"},{"@type":"ListItem","position":2,"name":"Lotte van Alderen. Foscofotogr&hellip;"}]},{"@type":"WebSite","@id":"https:\/\/www.originalphotopaper.com\/pl\/#website","url":"https:\/\/www.originalphotopaper.com\/pl\/","name":"Original Photo Paper by FUJIFILM","description":"DISCOVER FUJIFILM ORIGINAL PHOTOGRAPHIC PAPERS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.originalphotopaper.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Person","@id":"https:\/\/www.originalphotopaper.com\/pl\/#\/schema\/person\/de751a26f5badc585d47e1934d237e47","name":"Arjen Janssen","image":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/secure.gravatar.com\/avatar\/6c9ddd5c119251f85fa34754a0dc67669f83c5e8594bd5650418c63a71343b6e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6c9ddd5c119251f85fa34754a0dc67669f83c5e8594bd5650418c63a71343b6e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6c9ddd5c119251f85fa34754a0dc67669f83c5e8594bd5650418c63a71343b6e?s=96&d=mm&r=g","caption":"Arjen Janssen"}}]}},"_links":{"self":[{"href":"https:\/\/www.originalphotopaper.com\/pl\/wp-json\/wp\/v2\/posts\/16033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.originalphotopaper.com\/pl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.originalphotopaper.com\/pl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.originalphotopaper.com\/pl\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.originalphotopaper.com\/pl\/wp-json\/wp\/v2\/comments?post=16033"}],"version-history":[{"count":0,"href":"https:\/\/www.originalphotopaper.com\/pl\/wp-json\/wp\/v2\/posts\/16033\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.originalphotopaper.com\/pl\/wp-json\/wp\/v2\/media\/16017"}],"wp:attachment":[{"href":"https:\/\/www.originalphotopaper.com\/pl\/wp-json\/wp\/v2\/media?parent=16033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.originalphotopaper.com\/pl\/wp-json\/wp\/v2\/categories?post=16033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.originalphotopaper.com\/pl\/wp-json\/wp\/v2\/tags?post=16033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}